
{"id":11210,"date":"2023-03-31T09:21:03","date_gmt":"2023-03-31T09:21:03","guid":{"rendered":"https:\/\/lenard.tech\/producto\/une-en-iso-6330\/"},"modified":"2026-07-14T11:55:32","modified_gmt":"2026-07-14T11:55:32","slug":"une-en-iso-63302022","status":"publish","type":"product","link":"https:\/\/lenard.tech\/fr\/producto\/une-en-iso-63302022\/","title":{"rendered":"UNE-EN ISO 6330:2022"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]PROC\u00c9DURES DE LAVAGE ET DE S\u00c9CHAGE DOMESTIQUE POUR LES ESSAIS TEXTILE. <em>\u00c9quivalence avec EN ISO 6330:2021 et ISO 6330:2021.<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_tta_tabs title_tag=&#8221;h3&#8243; section_title_tag=&#8221;h3&#8243; style=&#8221;modern&#8221; color=&#8221;white&#8221; active_section=&#8221;1&#8243; no_fill_content_area=&#8221;true&#8221;][vc_tta_section title=&#8221;OBJET&#8221; tab_id=&#8221;1685522856905-7d802a20-a20ae3bf-ea08&#8243; el_class=&#8221;Bold&#8221;][vc_column_text woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Cette norme pr\u00e9cise les proc\u00e9dures domestiques de lavage et de s\u00e9chage pour les tests textiles. Ces proc\u00e9dures s&#8217;appliquent aux tissus, v\u00eatements ou autres articles textiles pr\u00eats \u00e0 l&#8217;emploi soumis \u00e0 des combinaisons appropri\u00e9es de lavage et de s\u00e9chage domestique.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;MAT\u00c9RIAUX ET \u00c9QUIPEMENTS&#8221; tab_id=&#8221;1687343259470-9968914a-53ec&#8221;][vc_column_text woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]APPAREILS<\/p>\n<p>-Machines \u00e0 laver automatiques :<\/p>\n<p>-Type A : Tambour horizontal, chargement frontal<\/p>\n<p>&#8211; Type B : Tambour vertical, agitateur \u00e0 chargement frontal<\/p>\n<p>&#8211; Type C : Tambour vertical, type bouton-poussoir \u00e0 chargement frontal<\/p>\n<p>-S\u00e8che-tambours :<\/p>\n<p>-Type A1 : \u00c9vacuation<\/p>\n<p>-Type A2 : Condensation<\/p>\n<p>-Type A3 : Grande \u00e9vacuation<\/p>\n<p>-Presse \u00e9lectrique plate pour le s\u00e9chage<\/p>\n<p>-Cordes \u00e0 linge avec environ 16 feuilles d&#8217;acier inoxydable ou de plastique pour le s\u00e9chage goutte \u00e0 goutte \u00e0 goutte ou \u00e0 plat.<\/p>\n<p>-Contrepoids<\/p>\n<p>-Type 1 : 100 % coton<\/p>\n<p>&#8211; Type 2 : 50 % coton \/ 50 % polyester<\/p>\n<p>-Type 3 : 100 % polyester<\/p>\n<p>-Autres : Si les parties int\u00e9ress\u00e9es l&#8217;ont accept\u00e9. Dans ce cas, cela doit \u00eatre indiqu\u00e9 dans le rapport de test<\/p>\n<p>R\u00c9ACTIFS :<\/p>\n<p>-D\u00e9tergents (voir composition nominale dans la norme) :<\/p>\n<p>-D\u00e9tergent de r\u00e9f\u00e9rence 1 : d\u00e9tergent en poudre sans phosphate ni enzymes, avec ou sans \u00e9claircissant optique. UNIQUEMENT POUR LES MACHINES DE TYPE B<\/p>\n<p>-D\u00e9tergent de r\u00e9f\u00e9rence 2 : sans phosphate, \u00e9claircissant optique, lessive en poudre sans enzymes. PEUT \u00caTRE UTILIS\u00c9 SUR DES MACHINES DE TYPE A ET B<\/p>\n<p>-D\u00e9tergent de r\u00e9f\u00e9rence 3 : d\u00e9tergent en poudre sans phosphate, enzymes ni blanchisseur optique. PEUT \u00caTRE UTILIS\u00c9 SUR DES MACHINES DE TYPE A ET B<\/p>\n<p>-D\u00e9tergent de r\u00e9f\u00e9rence 4 : sans phosphate, \u00e9claircissant optique, lessive en poudre sans enzymes. UNIQUEMENT POUR LES MACHINES DE TYPE C<\/p>\n<p>-D\u00e9tergent de r\u00e9f\u00e9rence 5 : la lessive liquide sans phosphate de l&#8217;AATCC. PLUS DISPONIBLE<\/p>\n<p>-D\u00e9tergent de r\u00e9f\u00e9rence 6 : d\u00e9tergent en poudre sans phosphate avec \u00e9claircisseur optique et sans enzymes. PEUT \u00caTRE UTILIS\u00c9 SUR DES MACHINES DE TYPE A.<\/p>\n<p>-D\u00e9tergent de r\u00e9f\u00e9rence 7 : d\u00e9tergent liquide pour la laine\/soie pour des proc\u00e9d\u00e9s doux\/d\u00e9licats. POUR LES TEXTILES D\u00c9LICATS OU POUR LE LAVAGE \u00c0 LA MAIN.<\/p>\n<p>-Eau : duret\u00e9 maximale 3,0 mmol\/l ; pression d&#8217;alimentation sup\u00e9rieure \u00e0 150 kPa ; temp\u00e9rature d&#8217;entr\u00e9e inf\u00e9rieure \u00e0 25 \u00b0C[\/vc_column_text][vc_single_image image=&#8221;11791&#8243; img_size=&#8221;FULL&#8221; alignment=&#8221;center&#8221; parallax_scroll=&#8221;no&#8221; woodmart_inline=&#8221;no&#8221;][vc_column_text woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]PROC\u00c9DURES DE S\u00c9CHAGE\u00a0:<br \/>\n\u2022 Proc\u00e9dure A S\u00e9chage sur ficelle<br \/>\n\u2022 Proc\u00e9dure B S\u00e9chage goutte \u00e0 goutte<br \/>\n\u2022 Proc\u00e9dure C S\u00e9chage \u00e0 plat<br \/>\n\u2022 Proc\u00e9dure D S\u00e9chage au fer plat<br \/>\n\u2022 Proc\u00e9dure E S\u00e9chage en tambour<\/p>\n<p>PROC\u00c9DURE DE S\u00c9CHAGE AU TAMBOUR\u00a0:<br \/>\n\u2022 M\u00eame charge dans le s\u00e8che-linge<br \/>\n\u2022 Les mesures du mat\u00e9riau sont d\u00e9termin\u00e9es et le s\u00e9chage se poursuit de sorte que l&#8217;humidit\u00e9 finale de la charge doit \u00eatre<br \/>\n\u00b1 2% pour les textiles synth\u00e9tiques, ou \u00b1 5% pour les textiles cellulosiques.<br \/>\n\u2022 La temp\u00e9rature de l&#8217;air \u00e9vacu\u00e9 du tambour est r\u00e9gl\u00e9e \u00e0 une valeur qui ne d\u00e9passe pas 70 \u00baC pour les tissus normaux et 50 \u00baC pour les tissus d\u00e9licats.<br \/>\n\u2022 L&#8217;utilisation de la vitesse de s\u00e9chage a pour le temps estim\u00e9 du cycle d&#8217;essai final, peut donner une valeur sous-estim\u00e9e de 5 %, d&#8217;o\u00f9 la n\u00e9cessit\u00e9 de r\u00e9p\u00e9ter l&#8217;op\u00e9ration pour compenser la diminution de la dur\u00e9e. Il est sugg\u00e9r\u00e9 que si les conditions environnementales de temp\u00e9rature et d&#8217;humidit\u00e9 relative sont raisonnablement coh\u00e9rentes, le taux de s\u00e9chage b n&#8217;est d\u00e9termin\u00e9 qu&#8217;une seule fois, mais en cas de variation, le taux de s\u00e9chage doit \u00eatre d\u00e9termin\u00e9 dans les nouvelles conditions.<\/p>\n<p>Le temps de cycle estim\u00e9 selon cette m\u00e9thode correspond \u00e0 2% du temps r\u00e9el mesur\u00e9 \u00e0 l&#8217;aide d&#8217;une \u00e9chelle appropri\u00e9e. Ce niveau de pr\u00e9cision est suffisant compte tenu du caract\u00e8re n\u00e9cessairement arbitraire des facteurs de surs\u00e9chage de fibres de nature diff\u00e9rente au sein d&#8217;une m\u00eame charge.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;PROC\u00c9DURE ET R\u00c9SULTATS&#8221; tab_id=&#8221;1685522856916-22531c7c-aaf1e3bf-ea08&#8243;][vc_column_text woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Conditionnement de l&#8217;\u00e9chantillon selon ISO 139<\/p>\n<p>PROC\u00c9DURE DE LAVAGE :<\/p>\n<p>&#8211; Obtenir une charge s\u00e8che totale de 2,0 \u00b1 0,2 kg (sp\u00e9cimens + contrepoids). Si le v\u00eatement complet est test\u00e9, la charge totale est enregistr\u00e9e si elle d\u00e9passe 2,2 kg. Le choix du contrepoids d\u00e9pendra des fibres de l&#8217;\u00e9chantillon :<\/p>\n<p>&#8211; Contrepoids de type I pour les sp\u00e9cimens contenant au moins 51 % de fibres cellulosiques<\/p>\n<p>&#8211; Contrepoids de type III pour les sp\u00e9cimens contenant au moins 51 % de fibres synth\u00e9tiques<\/p>\n<p>&#8211; Contrepoids de type II ou III pour les sp\u00e9cimens contenant d&#8217;autres fibres ou m\u00e9langes.<\/p>\n<p>&#8211; Les \u00e9chantillons ne doivent pas repr\u00e9senter plus de la moiti\u00e9 de la charge de lavage si l&#8217;on veut d\u00e9terminer la stabilit\u00e9 dimensionnelle.<\/p>\n<p>-La proc\u00e9dure de lavage est choisie. Les \u00e9chantillons sont pes\u00e9s avant lavage et, si n\u00e9cessaire, un contrepoids est ajout\u00e9 pour supporter la charge requise de la machine \u00e0 laver. M\u00e9langez les \u00e9chantillons uniform\u00e9ment avec les contrepoids avant de les charger dans la machine \u00e0 laver.<\/p>\n<p>-Ajouter la lessive :<\/p>\n<p>-Machines \u00e0 laver Type A : 20 \u00b1 1 g dans le distributeur. Pour les v\u00eatements d\u00e9licats ou la laine, 47 \u00b1 1 g.<\/p>\n<p>&#8211; Machines \u00e0 laver de type B : 66 \u00b1 1 g si c&#8217;est un d\u00e9tergent de r\u00e9f\u00e9rence 1. S&#8217;il s&#8217;agit d&#8217;un d\u00e9tergent de r\u00e9f\u00e9rence 2 ou 3, la bonne quantit\u00e9 pour obtenir une mousse d&#8217;une hauteur ne d\u00e9passant pas 3 \u00b1 0,5 cm \u00e0 la fin du cycle de lavage.<\/p>\n<p>&#8211; Machine \u00e0 laver de type C : 1,33 g\/l de d\u00e9tergente de r\u00e9f\u00e9rence 4 dans le distributeur.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Proc\u00e9dure de lavage pour machine \u00e0 laver de type A<\/p>\n<table style=\"height: 1397px;\" width=\"1603\">\n<tbody>\n<tr>\n<td rowspan=\"4\" width=\"70\">Proc\u00e9dure<\/p>\n<p>N<\/td>\n<td rowspan=\"4\" width=\"74\">Agitation lors du chauffage, du lavage et du rin\u00e7age<\/td>\n<td colspan=\"4\" width=\"223\">Lavage<\/td>\n<td colspan=\"2\" width=\"106\">Premier rin\u00e7age<\/td>\n<td colspan=\"3\" width=\"149\">2e rin\u00e7age<\/td>\n<td colspan=\"3\" width=\"141\">3e rin\u00e7age<\/td>\n<td colspan=\"3\" width=\"139\">4e d\u00e9gagement<\/td>\n<\/tr>\n<tr>\n<td width=\"66\">Temp\u00e9rature<\/td>\n<td width=\"47\">Niveau de fluide<\/td>\n<td width=\"44\">Temps de lavage<\/td>\n<td width=\"66\">Refroidissement<\/td>\n<td width=\"50\">Niveau de fluide<\/td>\n<td width=\"56\">Rin\u00e7age<\/td>\n<td width=\"55\">Niveau de fluide<\/td>\n<td width=\"48\">Rin\u00e7age<\/td>\n<td width=\"46\">Le temps de tourn\u00e9e<\/td>\n<td width=\"46\">Niveau de fluide<\/td>\n<td width=\"48\">Rin\u00e7age<\/td>\n<td width=\"46\">Le temps de tourn\u00e9e<\/td>\n<td width=\"46\">Niveau de fluide<\/td>\n<td width=\"48\">Rin\u00e7age<\/td>\n<td width=\"44\">Le temps de tourn\u00e9e<\/td>\n<\/tr>\n<tr>\n<td width=\"66\"><sup>a<\/sup><\/td>\n<td width=\"47\"><sup>BC<\/sup><\/td>\n<td width=\"44\"><sup>d<\/sup><\/td>\n<td width=\"66\"><sup>f<\/sup><\/td>\n<td width=\"50\"><sup>BC<\/sup><\/td>\n<td width=\"56\"><sup>DG<\/sup><\/td>\n<td width=\"55\"><sup>BC<\/sup><\/td>\n<td width=\"48\"><sup>DG<\/sup><\/td>\n<td width=\"46\"><sup>d<\/sup><\/td>\n<td width=\"46\"><sup>BC<\/sup><\/td>\n<td width=\"48\"><sup>DG<\/sup><\/td>\n<td width=\"46\"><sup>d<\/sup><\/td>\n<td width=\"46\"><sup>BC<\/sup><\/td>\n<td width=\"48\"><sup>bg<\/sup><\/td>\n<td width=\"44\"><sup>d<\/sup><\/td>\n<\/tr>\n<tr>\n<td width=\"66\">\u00baC<\/td>\n<td width=\"47\">Mm<\/td>\n<td width=\"44\">Min<\/td>\n<td width=\"66\"><\/td>\n<td width=\"50\">Mm<\/td>\n<td width=\"56\">Min<\/td>\n<td width=\"55\">Mm<\/td>\n<td width=\"48\">Min<\/td>\n<td width=\"46\">Min<\/td>\n<td width=\"46\">Mm<\/td>\n<td width=\"48\">Min<\/td>\n<td width=\"46\">Min<\/td>\n<td width=\"46\">Mm<\/td>\n<td width=\"48\">Min<\/td>\n<td width=\"44\">Min<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">9N<\/td>\n<td width=\"74\">Normal<\/td>\n<td width=\"66\">92 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Oui<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"44\">5<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">7N<\/td>\n<td width=\"74\">Normal<\/td>\n<td width=\"66\">70 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Oui<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"44\">5<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">6N<\/td>\n<td width=\"74\">Normal<\/td>\n<td width=\"66\">60 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"44\">5<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">6M<\/td>\n<td width=\"74\">Moyen<\/td>\n<td width=\"66\">60 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">2j<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">5N<\/td>\n<td width=\"74\">Normal<\/td>\n<td width=\"66\">50 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"44\">5<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">5M<\/td>\n<td width=\"74\">Moyen<\/td>\n<td width=\"66\">50 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">2j<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">4N<\/td>\n<td width=\"74\">Normal<\/td>\n<td width=\"66\">40 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"44\">5<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">4M<\/td>\n<td width=\"74\">Moyen<\/td>\n<td width=\"66\">40 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">2j<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">4G<\/td>\n<td width=\"74\">Souple*<\/td>\n<td width=\"66\">40 \u00b1 3<\/td>\n<td width=\"47\">130<\/td>\n<td width=\"44\">3<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">1<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">6<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">3N<\/td>\n<td width=\"74\">Normal<\/td>\n<td width=\"66\">30 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"44\">5<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">3M<\/td>\n<td width=\"74\">Moyen<\/td>\n<td width=\"66\">30 \u00b1 3<\/td>\n<td width=\"47\">100<\/td>\n<td width=\"44\">15<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">2j<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">3G<\/td>\n<td width=\"74\">Souple*<\/td>\n<td width=\"66\">30 \u00b1 3<\/td>\n<td width=\"47\">130<\/td>\n<td width=\"44\">3<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">3<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">2j<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">3H<\/td>\n<td width=\"74\">Souple*<\/td>\n<td width=\"66\">30 \u00b1 3<\/td>\n<td width=\"47\">130<\/td>\n<td width=\"44\">1<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">4H<\/td>\n<td width=\"74\">Sourple*<\/td>\n<td width=\"66\">40 \u00b1 3<\/td>\n<td width=\"47\">130<\/td>\n<td width=\"44\">1<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">2<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">3HD<\/td>\n<td width=\"74\">Souple*<\/td>\n<td width=\"66\">30 \u00b1 3<\/td>\n<td width=\"47\">130<\/td>\n<td width=\"44\">1<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">20 s<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\">4HD<\/td>\n<td width=\"74\">Souple*<\/td>\n<td width=\"66\">40 \u00b1 3<\/td>\n<td width=\"47\">130<\/td>\n<td width=\"44\">1<\/td>\n<td width=\"66\">Non<\/td>\n<td width=\"50\">130<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"55\">130<\/td>\n<td width=\"48\">2<\/td>\n<td width=\"46\">20 s<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"46\">&#8211;<\/td>\n<td width=\"48\">&#8211;<\/td>\n<td width=\"44\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td width=\"70\"><\/td>\n<td width=\"74\"><\/td>\n<td width=\"66\"><\/td>\n<td width=\"47\"><\/td>\n<td width=\"44\"><\/td>\n<td width=\"66\"><\/td>\n<td width=\"50\"><\/td>\n<td width=\"56\"><\/td>\n<td width=\"55\"><\/td>\n<td width=\"48\"><\/td>\n<td width=\"46\"><\/td>\n<td width=\"46\"><\/td>\n<td width=\"48\"><\/td>\n<td width=\"46\"><\/td>\n<td width=\"46\"><\/td>\n<td width=\"48\"><\/td>\n<td width=\"44\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>N \u2192 agitation normale : 12 s et 3 s de mouvement statique du tambour. Centrifugation \u00e9lev\u00e9e<\/p>\n<p>M \u2192 Medium Stirring : 8 s et 7 s de mouvement statique de tambour. Faible centrifugation<\/p>\n<p>G \u2192 Mouvement doux : mouvement statique de tambour de 3 s et 12 s. Faible centrifugation<\/p>\n<p>H \u2192 Lavage de mains simul\u00e9 : secousses douces : mouvement statique de tambour de 3 s et 12 s. Faible centrifugation<\/p>\n<p>Drain d&#8217;eau de la machine\u00e0 \u00e0 laver HD\u00a0 sans extraction par centrifugation<\/p>\n<p>r \u00e0 La temp\u00e9rature principale de lavage fait r\u00e9f\u00e9rence \u00e0 la temp\u00e9rature d&#8217;arr\u00eat<\/p>\n<p>b \u2192 Le niveau de liquide est mesur\u00e9 au fond du tambour apr\u00e8s 1 minute de fonctionnement et 30 s d&#8217;arr\u00eat<\/p>\n<p>c \u2192 Dans les machines \u00e0 laver de type A1 : la mesure de volume est utilis\u00e9e pour une plus grande pr\u00e9cision. Voir le tableau B2 de la norme<\/p>\n<p>d \u2192 Une tol\u00e9rance de \u00b1 20 s peut \u00eatre appliqu\u00e9e aux moments indiqu\u00e9s<\/p>\n<p>et \u2192 sans agitation lors du chauffage de l&#8217;eau \u00e0 la temp\u00e9rature fix\u00e9e de -5 \u00b0C. \u00c0 partir de la temp\u00e9rature r\u00e9gl\u00e9e de -5 \u00baC, elle est l\u00e9g\u00e8rement secou\u00e9e. L&#8217;expression \u00ab Tr\u00e8s doux \u00bb dans l&#8217;ISO 3758 correspond \u00e0 un \u00ab doux \u00bb dans l&#8217;ISO 6330 pour des raisons pratiques (mn\u00e9motechniques) de se souvenir du cycle de lavage.<\/p>\n<p>f \u2192 Refroidissement : de l&#8217;eau froide jusqu&#8217;\u00e0 130 mm est ajout\u00e9e et remu\u00e9e pendant 2 minutes suppl\u00e9mentaires.<\/p>\n<p>g \u2192 Le temps de rin\u00e7age est mesur\u00e9 lorsque le niveau de liquide est atteint<\/p>\n<p>H \u2192 est chauff\u00e9 \u00e0 40 \u00baC et conserv\u00e9 pendant 15 minutes avec agitation avant de chauffer \u00e0 temp\u00e9rature de lavage.<\/p>\n<p>I \u2192 Pour des pratiques de laboratoire s\u00fbres uniquement<\/p>\n<p>j \u2192 Spin court<\/p>\n<p>S\u00e9chage goutte\u00e0 \u00e0 goutte k<\/p>\n<p>&nbsp;<\/p>\n<p>Proc\u00e9dure de lavage pour machines \u00e0 laver de type B<\/p>\n<table style=\"height: 739px;\" width=\"1543\">\n<tbody>\n<tr>\n<td width=\"153\">Cycle<\/td>\n<td width=\"153\">Normal<\/td>\n<td width=\"153\">D\u00e9licate<\/td>\n<td width=\"153\">Repassage permanent<\/td>\n<\/tr>\n<tr>\n<td width=\"153\">Niveau d&#8217;eau, l (gal)<\/td>\n<td colspan=\"3\" width=\"460\">72 \u00b1 4 (19 \u00b1 1)<\/td>\n<\/tr>\n<tr>\n<td width=\"153\">Vitesse de brassage (coups\/min)<\/td>\n<td width=\"153\">86 \u00b1 2<\/td>\n<td width=\"153\">27 \u00b1 2<\/td>\n<td width=\"153\">86 \u00b1 2<\/td>\n<\/tr>\n<tr>\n<td width=\"153\">C&#8217;est l&#8217;heure du lavage, min<\/td>\n<td width=\"153\">16<\/td>\n<td width=\"153\">8.5<\/td>\n<td width=\"153\">12<\/td>\n<\/tr>\n<tr>\n<td width=\"153\">Vitesse finale de rotation (r\/min)<\/td>\n<td width=\"153\">660 \u00b1 15<\/td>\n<td width=\"153\">500 \u00b1 15<\/td>\n<td width=\"153\">500 \u00b1 15<\/td>\n<\/tr>\n<tr>\n<td width=\"153\">Temps final de rotation (min)<\/td>\n<td colspan=\"3\" width=\"460\">5<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\" width=\"153\">Temp\u00e9rature de lavage \u00baC (\u00baF)<sup>a<\/sup><\/td>\n<td colspan=\"3\" width=\"460\">Froid : 27 \u00b1 3 (80 \u00b1 5)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\" width=\"460\">Temp\u00e9rament : 41 \u00b1 3 (105 \u00b1 5)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\" width=\"460\">Chaud : 49 \u00b1 3 (120 \u00b1 5)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\" width=\"460\">Tr\u00e8s chaud : 60 \u00b1 3 (140 \u00b1 5)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><sup>a \u2192<\/sup>\u00a0Les temp\u00e9ratures de ce tableau sont similaires \u00e0 celles sp\u00e9cifi\u00e9es par la Federal Trade Commission des \u00c9tats-Unis pour la v\u00e9rification des labels de soins. En raison des exigences du D\u00e9partement de l&#8217;\u00c9nergie de la DUL, de nombreuses machines \u00e0 laver grand public utilisent de l&#8217;eau plus fra\u00eeche. Une bo\u00eete de contr\u00f4le externe peut \u00eatre utilis\u00e9e pour contourner les temp\u00e9ratures r\u00e9gl\u00e9es par la machine.<\/p>\n<p>Proc\u00e9dure de lavage pour les machines \u00e0 laver de type C<\/p>\n<table style=\"height: 758px;\" width=\"1531\">\n<tbody>\n<tr>\n<td rowspan=\"4\" width=\"77\">Proc\u00e9dure<\/p>\n<p>N<\/td>\n<td rowspan=\"4\" width=\"55\">Agitation lors du lavage et du rin\u00e7age<\/td>\n<td colspan=\"4\" width=\"208\">Lavage<\/td>\n<td colspan=\"3\" width=\"137\">Rincez 1b<\/td>\n<td colspan=\"3\" width=\"137\">Rincez 2b<\/td>\n<\/tr>\n<tr>\n<td width=\"71\">Temp\u00e9rature<\/td>\n<td width=\"43\">Niveau de fluide<\/td>\n<td width=\"47\">Temps de lavage<\/td>\n<td width=\"47\">Le temps de tourn\u00e9e<\/td>\n<td width=\"43\">Niveau de fluide<\/td>\n<td width=\"47\">Tiempo<\/td>\n<td width=\"47\">Le temps de tourn\u00e9e<\/td>\n<td width=\"43\">Niveau de fluide<\/td>\n<td width=\"47\">Tiempo<\/td>\n<td width=\"47\">Le temps de tourn\u00e9e<\/td>\n<\/tr>\n<tr>\n<td width=\"71\">\u00baC<\/td>\n<td width=\"43\">I<\/td>\n<td width=\"47\">min<\/td>\n<td width=\"47\">min<\/td>\n<td width=\"43\">I<\/td>\n<td width=\"47\">min<\/td>\n<td width=\"47\">min<\/td>\n<td width=\"43\">I<\/td>\n<td width=\"47\">min<\/td>\n<td width=\"47\">min<\/td>\n<\/tr>\n<tr>\n<td width=\"71\"><sup>a<\/sup><\/td>\n<td width=\"43\">&#8211;<\/td>\n<td width=\"47\">&#8211;<\/td>\n<td width=\"47\"><sup>e<\/sup><\/td>\n<td width=\"43\">&#8211;<\/td>\n<td width=\"47\">&#8211;<\/td>\n<td width=\"47\"><sup>e<\/sup><\/td>\n<td width=\"43\">&#8211;<\/td>\n<td width=\"47\">&#8211;<\/td>\n<td width=\"47\"><sup>e<\/sup><\/td>\n<\/tr>\n<tr>\n<td width=\"77\">4N<\/td>\n<td width=\"55\">Normal<sup>C<\/sup><\/td>\n<td width=\"71\">40 \u00b1 3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">15<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">7<\/td>\n<\/tr>\n<tr>\n<td width=\"77\">4M<\/td>\n<td width=\"55\">Normal<sup>C<\/sup><\/td>\n<td width=\"71\">40 \u00b1 3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">6<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<\/tr>\n<tr>\n<td width=\"77\">4G<\/td>\n<td width=\"55\">Normal<sup>C<\/sup><\/td>\n<td width=\"71\">40 \u00b1 3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">\u2264 1<\/td>\n<\/tr>\n<tr>\n<td width=\"77\">3N<\/td>\n<td width=\"55\">Normal<sup>C<\/sup><\/td>\n<td width=\"71\">30 \u00b1 3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">15<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">7<\/td>\n<\/tr>\n<tr>\n<td width=\"77\">3M<\/td>\n<td width=\"55\">Normal<sup>C<\/sup><\/td>\n<td width=\"71\">30 \u00b1 3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">6<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<\/tr>\n<tr>\n<td width=\"77\">3G<\/td>\n<td width=\"55\">Normal<sup>C<\/sup><\/td>\n<td width=\"71\">30 \u00b1 3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">3<\/td>\n<td width=\"43\">40<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">\u2264 1<\/td>\n<\/tr>\n<tr>\n<td width=\"77\">4H<\/td>\n<td width=\"55\">\u00e9l\u00e9gant<\/td>\n<td width=\"71\">40 \u00b1 3<\/td>\n<td width=\"43\">54<\/td>\n<td width=\"47\">6<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"43\">54<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"43\">54<\/td>\n<td width=\"47\">2<\/td>\n<td width=\"47\">\u2264 1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>a \u2192 L&#8217;eau de lavage est pr\u00e9chauff\u00e9e \u00e0 la temp\u00e9rature d\u00e9sign\u00e9e et fournie \u00e0 la machine \u00e0 laver<\/p>\n<p>b \u2192 Pour le rin\u00e7age, de l&#8217;eau froide est utilis\u00e9e et fournie par un robinet maison<\/p>\n<p>c \u2192 L&#8217;agitation normale est l&#8217;action de rotation, telle qu&#8217;un cycle, avec un taux de pulsation normal avec l&#8217;agitation 0,8 s activ\u00e9e et 0,6 s \u00e9teinte, suivie d&#8217;une agitation inverse pendant 0,8 s allum\u00e9e et 0,6 s \u00e9teinte.<\/p>\n<p>d \u2192 La proc\u00e9dure 4H est un lavage des mains simul\u00e9 avec un l\u00e9ger secouement correspondant \u00e0 l&#8217;action rotative, comme un cycle, avec une pulsation douce avec 1,3 s de secouement allum\u00e9 et 5,8 s d&#8217;arr\u00eat, suivi d&#8217;un secouement invers\u00e9 pendant 1,3 s allum\u00e9 et 5,8 s d&#8217;arr\u00eat.<\/p>\n<p>e \u2192 Dans le cas 4H, la rotation correspond \u00e0 la plus basse rotation de la vitesse du tambour lors de la rotation, tandis que dans le reste du cas, la rotation est la plus grande.<\/p>\n<p>&nbsp;<\/p>\n<p>PROC\u00c9DURES DE S\u00c9CHAGE :<\/p>\n<p>-Une fois le lavage termin\u00e9, le mat\u00e9riau est imm\u00e9diatement retir\u00e9 et l&#8217;une des proc\u00e9dures de s\u00e9chage est suivie :<\/p>\n<p>-Proc\u00e9dure Un s\u00e9chage \u00e0 l&#8217;air. La cha\u00eene doit \u00eatre verticale<\/p>\n<p>-Proc\u00e9dure B : S\u00e9chage de la ligne de goutte-\u00e0-goutte.<\/p>\n<p>-Proc\u00e9dure C S\u00e9chage \u00e0 plat<\/p>\n<p>-Proc\u00e9dure D S\u00e9chage goutte \u00e0 goutte plate<\/p>\n<p>-Proc\u00e9dure E S\u00e9chage sur une plaque<\/p>\n<p>-Proc\u00e9dure S\u00e9chage de tambour en Fa<\/p>\n<p>-Une fois le cycle de lavage termin\u00e9, retirez la charge (cylindres et contrepoids) et mettez-la dans le s\u00e8che-linge. Assurez-vous que la temp\u00e9rature de l&#8217;air \u00e9vacuant est r\u00e9gul\u00e9e \u00e0 au moins 40 \u00baC sans d\u00e9passer 80 \u00baC pour une temp\u00e9rature normale et 60 \u00baC pour une temp\u00e9rature basse.<\/p>\n<p>-Si le point final du cycle de s\u00e9chage d\u00e9pend de la teneur en humidit\u00e9 et du temps de fixation, il doit avoir une humidit\u00e9 \u00e9quivalente \u00e0 celle du textile conditionn\u00e9. Continuez \u00e0 s\u00e9cher pendant 5 minutes sans chauffage et retirez l&#8217;\u00e9chantillon.<\/p>\n<p>-Si le point final du cycle de s\u00e9chage est l&#8217;\u00e9tat de surs\u00e9chage et de fixation du temps, cela se caract\u00e9rise par le s\u00e9chage jusqu&#8217;\u00e0 ce que l&#8217;humidit\u00e9 finale soit inf\u00e9rieure \u00e0 celle du textile conditionn\u00e9. Dans ces cas, les pourcentages suivants de l&#8217;humidit\u00e9 finale seront appliqu\u00e9s :<\/p>\n<p>-2 % pour un textile compos\u00e9 de mat\u00e9riaux synth\u00e9tiques, par rapport \u00e0 la masse de l&#8217;\u00e9chantillon pr\u00e9sent\u00e9.<\/p>\n<p>-5 % pour un textile compos\u00e9 de mat\u00e9riaux cellulosiques, par rapport \u00e0 la masse de l&#8217;\u00e9chantillon conditionn\u00e9.<\/p>\n<p>-Pour les textiles fabriqu\u00e9s \u00e0 partir d&#8217;autres fibres et m\u00e9langes, consultez les ressources appropri\u00e9es pour l&#8217;humidit\u00e9 finale.<\/p>\n<p>-Si la teneur en humidit\u00e9 \u00e0 l&#8217;extr\u00e9mit\u00e9 est prise en charge par le capteur automatique du s\u00e8che-linge, elle s\u00e9chera jusqu&#8217;\u00e0 ce que le capteur atteigne le niveau convenu plus 5 minutes sans chauffage.<\/p>\n<p>-Cycle de s\u00e9chage 1 pour le coton sec avec une humidit\u00e9 finale de 0 \u00b1 3 %<\/p>\n<p>&#8211; Cycle de s\u00e9chage 2 pour les synth\u00e9tiques et m\u00e9lange avec une humidit\u00e9 finale de 2 \u00b1 3 %<\/p>\n<p>-Cycle de s\u00e9chage 3 pour le coton sec pour le fer avec une humidit\u00e9 finale de 12 \u00b1 3 %<\/p>\n<p>-Pour tous les textiles s\u00e9ch\u00e9s au temps de fixation, le point final doit se situer entre 0 % et -3 % de la masse:<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>PROC\u00c9DURES DE LAVAGE ET DE S\u00c9CHAGE DOMESTIQUE POUR LES ESSAIS TEXTILE. <span style=\"color: #ffff99;\"><em>\u00c9quivalence avec EN ISO 6330:2021 et ISO 6330:2021.<\/em><\/span><\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[884],"product_tag":[4056,4071,4077,4083,1644,1688,3545,3703,1809,1910,1498],"class_list":["post-11210","product","type-product","status-publish","hentry","product_cat-norme","product_tag-420-fr","product_tag-440-fr","product_tag-455-fr","product_tag-460-fr","product_tag-anticorte-fr","product_tag-antistatic-fr","product_tag-cardigan-fr","product_tag-lenard-fr","product_tag-tecvin-fr","product_tag-valen-t-fr","product_tag-xispal-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/lenard.tech\/fr\/wp-json\/wp\/v2\/product\/11210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lenard.tech\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lenard.tech\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lenard.tech\/fr\/wp-json\/wp\/v2\/comments?post=11210"}],"wp:attachment":[{"href":"https:\/\/lenard.tech\/fr\/wp-json\/wp\/v2\/media?parent=11210"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lenard.tech\/fr\/wp-json\/wp\/v2\/product_cat?post=11210"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lenard.tech\/fr\/wp-json\/wp\/v2\/product_tag?post=11210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}